﻿{"id":922,"date":"2020-08-04T16:57:11","date_gmt":"2020-08-04T19:57:11","guid":{"rendered":"https:\/\/www.quickbuffet.com.br\/cms\/?p=922"},"modified":"2020-08-05T09:43:17","modified_gmt":"2020-08-05T12:43:17","slug":"cardapio-opcoes-de-almocos","status":"publish","type":"post","link":"https:\/\/www.quickbuffet.com.br\/cms\/cardapio-opcoes-de-almocos\/","title":{"rendered":"Card\u00e1pio &#8211; Op\u00e7\u00f5es de Almo\u00e7os"},"content":{"rendered":"\n<p>Op\u00e7\u00f5es de Almo\u00e7o a R$ 26,00 (vinte e seis reais)<\/p>\n\n\n\n<p>Ligue com um dia de anteced\u00eancia que a gente prepara pra voce.<\/p>\n\n\n\n<p>Obs: aceitamos todos os vales refei\u00e7\u00e3o<\/p>\n\n\n\n<p><strong>Segunda<\/strong>:<\/p>\n\n\n\n<p>&#8211; 1 Suco de 250 ml de laranja.<\/p>\n\n\n\n<p>&#8211; Salada de folhas.<\/p>\n\n\n\n<p>&#8211; Arroz e feij\u00e3o.<\/p>\n\n\n\n<p>&#8211; Picadinho de ac\u00e9m com cenoura e batata.<\/p>\n\n\n\n<p>&#8211; Mousse de chocolate.<\/p>\n\n\n\n<p><strong>Ter\u00e7a<\/strong>:<\/p>\n\n\n\n<p>&#8211; 1 Suco de 250ml de uva.<\/p>\n\n\n\n<p>&#8211; Salada de folhas.<\/p>\n\n\n\n<p>&#8211; Arroz branco.<\/p>\n\n\n\n<p>&#8211; Batata palha.<\/p>\n\n\n\n<p>&#8211; Estrogonofe de frango.<\/p>\n\n\n\n<p>&#8211; Mousse de maracuj\u00e1.<\/p>\n\n\n\n<p><strong>Quarta<\/strong>:<\/p>\n\n\n\n<p>&#8211; 1 Suco de 250ml de laranja.<\/p>\n\n\n\n<p>&#8211; Couve manteiga.<\/p>\n\n\n\n<p>&#8211; Arroz.<\/p>\n\n\n\n<p>&#8211; Farofa.<\/p>\n\n\n\n<p>&#8211; Feijoada light.<\/p>\n\n\n\n<p>&#8211; Mousse de lim\u00e3o.<\/p>\n\n\n\n<p><strong>Quinta<\/strong>:<\/p>\n\n\n\n<p>&#8211; 1 Suco de 250ml de uva.<\/p>\n\n\n\n<p>&#8211; Salada de folhas.<\/p>\n\n\n\n<p>&#8211; Lasanha de queijo, presunto e molho de tomate.<\/p>\n\n\n\n<p>&#8211; Torta de frango.<\/p>\n\n\n\n<p>&#8211; Bolo de prest\u00edgio.<\/p>\n\n\n\n<p><strong>Sexta<\/strong>:<\/p>\n\n\n\n<p>&#8211; 1 Suco de 250ml de laranja.<\/p>\n\n\n\n<p>&#8211; Salada de folhas.<\/p>\n\n\n\n<p>&#8211; Macarr\u00e3o com porpetas e molho de tomates.<\/p>\n\n\n\n<p>&#8211; Torta de legumes.<\/p>\n\n\n\n<p>&#8211; Bolo de abacaxi.&nbsp;<\/p>\n\n\n\n<p>Aguardamos seus pedidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Op\u00e7\u00f5es de Almo\u00e7o a R$ 26,00 (vinte e seis reais) Ligue com um dia de anteced\u00eancia que a gente prepara pra voce. Obs: aceitamos todos os vales refei\u00e7\u00e3o Segunda: &#8211; 1 Suco de 250 ml de laranja. &#8211; Salada de folhas. &#8211; Arroz e feij\u00e3o. &#8211; Picadinho de ac\u00e9m com cenoura e batata. &#8211; Mousse <a href=\"https:\/\/www.quickbuffet.com.br\/cms\/cardapio-opcoes-de-almocos\/\" rel=\"nofollow\"><span class=\"sr-only\">Leia mais sobreCard\u00e1pio &#8211; Op\u00e7\u00f5es de Almo\u00e7os<\/span>[&hellip;]<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-922","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/www.quickbuffet.com.br\/cms\/wp-json\/wp\/v2\/posts\/922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.quickbuffet.com.br\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.quickbuffet.com.br\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.quickbuffet.com.br\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.quickbuffet.com.br\/cms\/wp-json\/wp\/v2\/comments?post=922"}],"version-history":[{"count":0,"href":"https:\/\/www.quickbuffet.com.br\/cms\/wp-json\/wp\/v2\/posts\/922\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.quickbuffet.com.br\/cms\/wp-json\/wp\/v2\/media?parent=922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.quickbuffet.com.br\/cms\/wp-json\/wp\/v2\/categories?post=922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.quickbuffet.com.br\/cms\/wp-json\/wp\/v2\/tags?post=922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}